{"id":33443,"date":"2024-03-20T23:59:00","date_gmt":"2024-03-21T02:59:00","guid":{"rendered":"https:\/\/revolutionarena.com\/pt-br\/?p=33443"},"modified":"2024-03-21T09:49:03","modified_gmt":"2024-03-21T12:49:03","slug":"data-de-lancamento-de-shin-megami-tensei-v-vengeance-e-adiantada-para-14-de-junho","status":"publish","type":"post","link":"https:\/\/revolutionarena.com\/pt-br\/data-de-lancamento-de-shin-megami-tensei-v-vengeance-e-adiantada-para-14-de-junho\/","title":{"rendered":"Data de lan\u00e7amento de\u00a0Shin Megami Tensei V: Vengeance\u00a0\u00e9 adiantada para 14 de junho"},"content":{"rendered":"\n<p>A ATLUS anunciou que a data de lan\u00e7amento do seu pr\u00f3ximo RPG, Shin Megami Tensei V: Vengeance, foi adiantada para 14 de junho de 2024. Agora, os f\u00e3s poder\u00e3o explorar Da&#8217;at uma semana mais cedo no Nintendo Switch, PlayStation 5, PlayStation 4, Xbox Series X|S, Xbox One, Windows e Steam, com op\u00e7\u00e3o de legendas em portugu\u00eas do Brasil.<\/p>\n\n\n\n<p>Mais recente t\u00edtulo da s\u00e9rie,&nbsp;<em>Shin Megami Tensei V: Vengeance<\/em>, permite que os jogadores desfrutem da hist\u00f3ria de&nbsp;<em>Shin Megami Tensei V<\/em>&nbsp;em sua totalidade, al\u00e9m de um novo caminho de hist\u00f3ria totalmente in\u00e9dito. O jogo chega evolu\u00eddo com visuais deslumbrantes adaptados para os consoles modernos e novas \u00e1reas, dem\u00f4nios e m\u00fasicas para apoiar um sistema de batalha aprimorado, proporcionando um RPG mais suave e rico, ambientado em meio a uma guerra entre anjos e dem\u00f4nios.<\/p>\n\n\n\n<p>Aqueles que aguardam para jogar a vers\u00e3o definitiva do aclamado jogo podem fazer a pr\u00e9-compra&nbsp;para Nintendo Switch, PlayStation 5, PlayStation 4, Xbox Series X|S, Xbox One, Windows e Steam (pr\u00e9-compras da edi\u00e7\u00e3o digital para Nintendo Switch vir\u00e3o em uma data posterior). Para aqueles que j\u00e1 fizeram a pr\u00e9-compra do jogo, nenhuma a\u00e7\u00e3o adicional \u00e9 necess\u00e1ria, o jogo estar\u00e1 dispon\u00edvel&nbsp;em 14 de junho.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A ATLUS anunciou que a data de lan\u00e7amento do seu pr\u00f3ximo RPG, Shin Megami Tensei V: Vengeance, foi adiantada para&hellip;<\/p>\n","protected":false},"author":1,"featured_media":33445,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"https:\/\/mcusercontent.com\/ef5b9476eedc3f79bb3048564\/images\/ea1284ff-232a-e8e1-52b2-4792a33ab6b2.png","fifu_image_alt":"","footnotes":""},"categories":[443,15,4,13,14],"tags":[],"class_list":["post-33443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-games","category-nintendo","category-noticias","category-playstation","category-xbox"],"_links":{"self":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts\/33443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/comments?post=33443"}],"version-history":[{"count":1,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts\/33443\/revisions"}],"predecessor-version":[{"id":33444,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts\/33443\/revisions\/33444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/media\/33445"}],"wp:attachment":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/media?parent=33443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/categories?post=33443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/tags?post=33443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}