{"id":33852,"date":"2024-04-10T22:55:14","date_gmt":"2024-04-11T01:55:14","guid":{"rendered":"https:\/\/revolutionarena.com\/pt-br\/?p=33852"},"modified":"2024-04-10T22:55:15","modified_gmt":"2024-04-11T01:55:15","slug":"beta-fechado-de-33-immortals-recebe-datas-oficiais","status":"publish","type":"post","link":"https:\/\/revolutionarena.com\/pt-br\/beta-fechado-de-33-immortals-recebe-datas-oficiais\/","title":{"rendered":"Beta fechado de 33 Immortals recebe datas oficiais"},"content":{"rendered":"\n<p>A desenvolvedora de jogos independente, Thunder Lotus, anunciou nesta quarta-feria (10) as datas do Beta Fechado de 33 Immortals, o jogo de a\u00e7\u00e3o-roguelike cooperativo para 33 jogadores. O teste Beta come\u00e7ar\u00e1 no dia 24 de maio de 2024 e seguir\u00e1 dispon\u00edvel at\u00e9 2 de junho de 2024. Os f\u00e3s que desejarem participar devem se inscrever no&nbsp;<a href=\"https:\/\/theogames.us18.list-manage.com\/track\/click?u=ef5b9476eedc3f79bb3048564&amp;id=6c211319db&amp;e=cb4b192de9\" target=\"_blank\" rel=\"noreferrer noopener\"><u>site<\/u><\/a>.<\/p>\n\n\n\n<p>Os jogadores que participarem do Beta ter\u00e3o a chance de desbloquear uma skin exclusiva para o jogo. 33 Immortals ser\u00e1 lan\u00e7ado em Acesso Antecipado na Epic Games Store, Xbox Series X|S, Windows PC e estar\u00e1 dispon\u00edvel no Xbox Game Pass para console e PC, ainda este ano.<\/p>\n\n\n\n<p>A desenvolvedora tamb\u00e9m anunciou um novo trailer da jogabilidade de 33 Immortals, que estreou durante a Iniciativa Triple-i, no YouTube. Confira o trailer\u00a0abaixo:<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"33 Immortals - Trailer Da Jogabilidade\" width=\"1140\" height=\"641\" src=\"https:\/\/www.youtube.com\/embed\/MBWzq0cqJOw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>O video oferece um foco maior nas principais caracter\u00edsticas de 33 Immortals, que incluem a emocionante coopera\u00e7\u00e3o de 33 jogadores, sua mec\u00e2nica suave de &#8220;pegar e saquear&#8221; e seu desafio aos jogadores para &#8220;enfrentar a ira de Deus&#8221;.<\/p>\n\n\n\n<p>Ap\u00f3s um per\u00edodo em Alpha bem-sucedido, o teste Beta Fechado de 33 Immortals \u00e9 o pr\u00f3ximo passo importante em um processo de desenvolvimento que se concentrou em uma colabora\u00e7\u00e3o estreita do jogo com sua comunidade, garantindo que o t\u00edtulo foque em seus pontos fortes durante a parte final da cria\u00e7\u00e3o. O Beta apresentar\u00e1 uma grande variedade de inimigos e ambientes, assim como um foco nas mec\u00e2nicas de colabora\u00e7\u00e3o de 33 Immortals.<\/p>\n\n\n\n<p>&#8220;33 Immortals teve um grande progresso nos poucos meses desde o Alpha,&#8221; disse o Diretor Criativo do t\u00edtulo, Stephan Logier, em comunicado. &#8220;Somos gratos aos nossos f\u00e3s pelos valiosos feedbacks que enviaram e por tudo que contribu\u00edram at\u00e9 o momento. Esperamos que eles achem a experi\u00eancia do Beta Fechado mais robusta e divertida tanto quanto n\u00f3s. Al\u00e9m disso, h\u00e1 uma skin exclusiva incr\u00edvel para ser resgatada nesse teste fechado para aqueles que estiverem \u00e0 altura do desafio proposto pelo jogo&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A desenvolvedora de jogos independente, Thunder Lotus, anunciou nesta quarta-feria (10) as datas do Beta Fechado de 33 Immortals, o&hellip;<\/p>\n","protected":false},"author":1,"featured_media":33854,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"https:\/\/mcusercontent.com\/ef5b9476eedc3f79bb3048564\/images\/e337b5b9-0502-f6d7-acee-86fb743d6440.png","fifu_image_alt":"","footnotes":""},"categories":[443,4,18,14],"tags":[],"class_list":["post-33852","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-games","category-noticias","category-pc","category-xbox"],"_links":{"self":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts\/33852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/comments?post=33852"}],"version-history":[{"count":1,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts\/33852\/revisions"}],"predecessor-version":[{"id":33853,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts\/33852\/revisions\/33853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/media\/33854"}],"wp:attachment":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/media?parent=33852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/categories?post=33852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/tags?post=33852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}