{"id":34070,"date":"2024-04-28T12:44:29","date_gmt":"2024-04-28T15:44:29","guid":{"rendered":"https:\/\/revolutionarena.com\/pt-br\/?p=34070"},"modified":"2024-04-30T18:33:54","modified_gmt":"2024-04-30T21:33:54","slug":"nintendo-switch-2-rumores-fortes-indicam-caracteristicas-intrigantes-do-futuro-console","status":"publish","type":"post","link":"https:\/\/revolutionarena.com\/pt-br\/nintendo-switch-2-rumores-fortes-indicam-caracteristicas-intrigantes-do-futuro-console\/","title":{"rendered":"Nintendo Switch 2: Rumores fortes indicam caracter\u00edsticas intrigantes do futuro console"},"content":{"rendered":"\n<p>Ol\u00e1 <strong>Nintendistas<\/strong>! Parece que o longo hiato de informa\u00e7\u00f5es sobre o <em>novo Nintendo Switch<\/em> foi interrompido. Aparentemente, fabricantes teriam conseguido acesso \u00e0 uma vers\u00e3o de mostru\u00e1rio do novo hardware.<\/p>\n\n\n\n<p>Os boatos sobre o pr\u00f3ximo console da Nintendo, que supostamente suceder\u00e1 o Nintendo Switch, continuam a se espalhar pela internet. Desta vez, as poss\u00edveis novidades v\u00eam dos fabricantes que est\u00e3o desenvolvendo os acess\u00f3rios para o novo hardware.<\/p>\n\n\n\n<p>De acordo com um artigo recente do portal espanhol <strong><a href=\"https:\/\/vandal.elespanol.com\/noticia\/1350770876\/se-filtran-mas-detalles-de-switch-2-cartuchos-compatibles-joycon-electromagneticos-con-mas-botones\/\" data-type=\"link\" data-id=\"https:\/\/vandal.elespanol.com\/noticia\/1350770876\/se-filtran-mas-detalles-de-switch-2-cartuchos-compatibles-joycon-electromagneticos-con-mas-botones\/\">Vandal<\/a><\/strong>, o jornalista <em>Rub\u00e9n Mercado<\/em> teve acesso a informa\u00e7\u00f5es privilegiadas sobre o novo sistema da Nintendo durante uma feira em que os fabricantes de acess\u00f3rios estavam presentes.<\/p>\n\n\n\n<p>Durante a feira, a <strong>Nintendo<\/strong> teria permitido que as empresas manipulassem uma caixa opaca para ter uma ideia das dimens\u00f5es do novo sistema, sem revelar o design final. Segundo as fontes, o novo hardware da Nintendo seria <em>um pouco maior<\/em> que o atual Switch, mas ainda <em>menor<\/em> que o Steam Deck da Valve. Al\u00e9m disso, foi mencionado que a Nintendo planeja utilizar um <em>sistema magn\u00e9tico para os novos controles<\/em>, o que poderia dificultar a compatibilidade f\u00edsica com os Joy-Con atuais que se encaixam nos trilhos do aparelho.<\/p>\n\n\n\n<p>Por fim, comentou-se que <em>o Pro Controller do Switch atual n\u00e3o ter\u00e1 problemas de compatibilidade com o novo sistema<\/em>, o que era de se esperar, j\u00e1 que ele se comunica via Bluetooth, assim como se presume que ser\u00e1 o caso dos potenciais novos Joy-Con.<\/p>\n\n\n\n<p>Quanto \u00e0 data de lan\u00e7amento, os fabricantes confirmam os rumores mais recentes de que o novo console da Nintendo dever\u00e1 chegar ao mercado global nos primeiros meses de 2025.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1 Nintendistas! Parece que o longo hiato de informa\u00e7\u00f5es sobre o novo Nintendo Switch foi interrompido. Aparentemente, fabricantes teriam conseguido&hellip;<\/p>\n","protected":false},"author":12,"featured_media":32252,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[443,15,4],"tags":[48,300,76],"class_list":["post-34070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-games","category-nintendo","category-noticias","tag-nintendo","tag-nintendo_switch","tag-switch"],"_links":{"self":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts\/34070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/comments?post=34070"}],"version-history":[{"count":1,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts\/34070\/revisions"}],"predecessor-version":[{"id":34071,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts\/34070\/revisions\/34071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/media\/32252"}],"wp:attachment":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/media?parent=34070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/categories?post=34070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/tags?post=34070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}