{"id":34089,"date":"2024-04-30T13:29:13","date_gmt":"2024-04-30T16:29:13","guid":{"rendered":"https:\/\/revolutionarena.com\/pt-br\/?p=34089"},"modified":"2024-04-30T13:32:04","modified_gmt":"2024-04-30T16:32:04","slug":"footgun-underground-chega-hoje-30-no-steam","status":"publish","type":"post","link":"https:\/\/revolutionarena.com\/pt-br\/footgun-underground-chega-hoje-30-no-steam\/","title":{"rendered":"Footgun: Underground chega hoje (30) no Steam"},"content":{"rendered":"\n<p>Um roguelike que bate um bol\u00e3o: essa \u00e9 a melhor forma de definir\u00a0<em><strong>Footgun: Underground<\/strong><\/em>! O game de estreia do est\u00fadio indie Turtle Knight Games em parceria com a publisher CobraTekku Games \u00e9 um roguelike viciante e repleto de a\u00e7\u00e3o no qual voc\u00ea chuta uma \u2013 ou v\u00e1rias \u2013 bolas contra monstros terr\u00edveis para mand\u00e1-los para o outro mundo e conseguir escapar de t\u00faneis subterr\u00e2neos. E vamos combinar: quem nunca teve a vontade de chutar seus advers\u00e1rios pra longe, n\u00e3o \u00e9 mesmo?\u00a0<em><strong>Footgun: Underground<\/strong><\/em>\u00a0est\u00e1\u00a0<strong>dispon\u00edvel agora no Steam<\/strong>, para PC e Steam Deck, por R$ 39,94<strong>,<\/strong>\u00a0valor que inclui um desconto de 15% que durar\u00e1 pelas primeiras duas semanas ap\u00f3s o lan\u00e7amento.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Footgun: Underground - Official Launch Trailer | Out Now On Steam!\" width=\"1140\" height=\"641\" src=\"https:\/\/www.youtube.com\/embed\/HkPwrnMcZyQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Em\u00a0<em><strong>Footgun: Underground<\/strong><\/em>\u00a0as bolas s\u00e3o parte central do gameplay e habilidade \u00e9 um caracter\u00edstica muito necess\u00e1ria. Isso porque \u00e9 preciso n\u00e3o apenas controlar as &#8220;redondas&#8221;, mas tamb\u00e9m usar elementos dos cen\u00e1rios, como paredes, plataformas, tetos e at\u00e9 mesmo outras bolas para eliminar at\u00e9 mesmo monstros que estejam escondidos. Ap\u00f3s cada n\u00edvel completado com sucesso \u2013 e eles s\u00e3o gerados aleatoriamente \u2013, tanto o personagem controlado quanto as bolas usadas podem ser aprimorados com v\u00e1rias habilidades e efeitos especiais. Chef\u00f5es derrotados tamb\u00e9m garantem recompensas especialmente valiosas, al\u00e9m de outros itens. E como cada personagem controlado tem caracter\u00edsticas \u00fanicas e o jogo usa morte permanente, cada partida \u00e9 uma verdadeira caixinha de surpresas.<\/p>\n\n\n\n<p>Devido ao seu gameplay divertido e cativante,\u00a0<em><strong>Footgun: Underground<\/strong><\/em>\u00a0foi indicado para o German Computer Game Award 2024 (DCP), que \u00e9 a principal premia\u00e7\u00e3o da Alemanha voltada a games e \u00e9 organizada em parceria pelo governo federal alem\u00e3o e pela Associa\u00e7\u00e3o da Ind\u00fastria de Games alem\u00e3. O game recebeu uma premia\u00e7\u00e3o de 25.000 euros por ser incluso na categoria de &#8220;Melhor Prot\u00f3tipo&#8221;.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/mcusercontent.com\/7a1bc338c984f6645b0ec681a\/images\/6bf34107-c9b1-8045-5feb-730207117773.jpg\" alt=\"\"\/><\/figure>\n<\/div>\n\n\n<p><strong>Principais caracter\u00edsticas\u00a0<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Um jogo que bate um bol\u00e3o<\/strong>\u00a0\u2013 Em\u00a0<em><strong>Footgun: Underground<\/strong><\/em>\u00a0boa parte do gameplay lembra um jogo de futebol, mas a a\u00e7\u00e3o r\u00e1pida faz dele uma experi\u00eancia \u00fanica.<\/li>\n\n\n\n<li><strong>A\u00e7\u00e3o em todas as esta\u00e7\u00f5es<\/strong>\u00a0\u2013 Partidas geradas aleatoriamente fazem com que cada n\u00edvel tenha desafios in\u00e9ditos.<\/li>\n\n\n\n<li><strong>Um metr\u00f4 selvagem<\/strong>\u00a0\u2013 5 biomas diferentes, repletos de 14 tipos distintos de inimigos p\u00f3s-apocal\u00edpticos e chef\u00f5es \u00fanicos exigem que os jogadores tenham total controle sobre a bola.<\/li>\n\n\n\n<li><strong>Aprimoramentos tecnol\u00f3gicos<\/strong>\u00a0\u2013 Al\u00e9m de melhorar seu personagem, voc\u00ea encontrar\u00e1 mais de 20 tipos diferentes de bolas com v\u00e1rios efeitos especiais, al\u00e9m de poder encontrar e equipar mais de 20 melhorias que afetam diretamente o gameplay.<\/li>\n\n\n\n<li><strong>Visual retr\u00f4\u00a0<\/strong>\u2013 O game \u00e9 feito totalmente em uma bela pixel art 2D.<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/mcusercontent.com\/7a1bc338c984f6645b0ec681a\/images\/d8192a32-f8b3-53b8-da05-3d2cbd13b2ee.jpg\" alt=\"\"\/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Um roguelike que bate um bol\u00e3o: essa \u00e9 a melhor forma de definir\u00a0Footgun: Underground! O game de estreia do est\u00fadio&hellip;<\/p>\n","protected":false},"author":1,"featured_media":34091,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"https:\/\/mcusercontent.com\/ef5b9476eedc3f79bb3048564\/images\/22d566fd-e715-91ba-7ddd-38e195d92d70.jpg","fifu_image_alt":"","footnotes":""},"categories":[443,4,18],"tags":[],"class_list":["post-34089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-games","category-noticias","category-pc"],"_links":{"self":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts\/34089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/comments?post=34089"}],"version-history":[{"count":2,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts\/34089\/revisions"}],"predecessor-version":[{"id":34093,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts\/34089\/revisions\/34093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/media\/34091"}],"wp:attachment":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/media?parent=34089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/categories?post=34089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/tags?post=34089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}