{"id":34599,"date":"2024-06-18T15:08:57","date_gmt":"2024-06-18T18:08:57","guid":{"rendered":"https:\/\/revolutionarena.com\/pt-br\/?p=34599"},"modified":"2024-06-18T15:08:58","modified_gmt":"2024-06-18T18:08:58","slug":"novos-jogos-no-game-pass-ea-sports-fc-24-my-time-at-sandrock-robin-hood-sherwood-builders-e-mais","status":"publish","type":"post","link":"https:\/\/revolutionarena.com\/pt-br\/novos-jogos-no-game-pass-ea-sports-fc-24-my-time-at-sandrock-robin-hood-sherwood-builders-e-mais\/","title":{"rendered":"Novos jogos no Game Pass: EA Sports FC 24, My Time at Sandrock, Robin Hood \u2013 Sherwood Builders e mais"},"content":{"rendered":"\n<p>A Microsoft anunciou uma s\u00e9rie de novos jogos que est\u00e3o chegando ao cat\u00e1logo do Game Pass. Confira os detalhes abaixo:<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Dispon\u00edvel Hoje<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Still Wakes the Deep<\/strong> (nuvem, PC e Xbox Series X|S): Um conto aterrorizante de isolamento em uma plataforma de petr\u00f3leo no Mar do Norte. Desenvolvido pela The Chinese Room, o jogo promete uma experi\u00eancia intensa de sobreviv\u00eancia.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Chegando em Breve<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>My Time at Sandrock<\/strong> (nuvem, console e PC) \u2013 19 de junho: Ambientado em um mundo p\u00f3s-apocal\u00edptico, os jogadores coletam recursos, constroem m\u00e1quinas e defendem a cidade de Sandrock de monstros, enquanto ajudam a salvar a cidade da ru\u00edna econ\u00f4mica.<\/li>\n\n\n\n<li><strong>Keplerth<\/strong> (PC) \u2013 20 de junho: Um RPG de sandbox 2D onde os jogadores devem sobreviver em um planeta alien\u00edgena hostil, seja sozinhos ou com amigos no modo multiplayer online.<\/li>\n\n\n\n<li><strong>EA Sports FC 24<\/strong> (nuvem, console e PC) EA Play \u2013 25 de junho: Chega ao Game Pass bem a tempo para a UEFA EURO 2024. Os jogadores podem liderar suas na\u00e7\u00f5es e competir pela gl\u00f3ria internacional.<\/li>\n\n\n\n<li><strong>SteamWorld Dig<\/strong> (nuvem e console) \u2013 26 de junho: Uma aventura de minera\u00e7\u00e3o com influ\u00eancias Metroidvania, onde os jogadores assumem o papel de Rusty, um steambot mineiro.<\/li>\n\n\n\n<li><strong>SteamWorld Dig 2<\/strong> (console e PC) \u2013 26 de junho: Retorna ao Game Pass, trazendo uma nova aventura de minera\u00e7\u00e3o em plataforma.<\/li>\n\n\n\n<li><strong>Robin Hood \u2013 Sherwood Builders<\/strong> (nuvem, PC e Xbox Series X|S) \u2013 27 de junho: Junte-se a Robin Hood em uma miss\u00e3o na Inglaterra do s\u00e9culo XII, completando miss\u00f5es, construindo uma aldeia secreta e explorando locais inspirados em mitos e hist\u00f3ria.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">DLCs e Atualiza\u00e7\u00f5es<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Minecraft: atualiza\u00e7\u00e3o Trick Trials<\/strong> \u2013 j\u00e1 dispon\u00edvel: Nova atualiza\u00e7\u00e3o com blocos decorativos, mobs hostis, itens, armas e c\u00e2maras de teste repletas de armadilhas e tesouros.<\/li>\n\n\n\n<li><strong>Smite: Summer Sizzle Pack<\/strong> \u2013 j\u00e1 dispon\u00edvel: Desbloqueie deuses e itens exclusivos no jogo de a\u00e7\u00e3o MOBA gratuito.<\/li>\n\n\n\n<li><strong>Monster Hunter Now: Pacote de nova temporada<\/strong> \u2013 j\u00e1 dispon\u00edvel: Inclui materiais de monstros e b\u00f4nus para celebrar a Temporada 2 de Monster Hunter Now.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Jogos Saindo em Breve<\/h4>\n\n\n\n<p>Os seguintes jogos deixar\u00e3o a biblioteca do Game Pass em breve. Aproveite os descontos de 20% para manter os jogos que voc\u00ea gosta.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Saindo em 30 de junho:<\/strong>\n<ul class=\"wp-block-list\">\n<li>FIFA 22 (Console e PC)<\/li>\n\n\n\n<li>F.I.S.T.: Forged In Shadow Torch (nuvem, console e PC)<\/li>\n\n\n\n<li>Stranded Deep (nuvem, console e PC)<\/li>\n\n\n\n<li>Story of Seasons: Friends of Mineral Town (nuvem, console e PC)<\/li>\n\n\n\n<li>Sword and Fairy Together Forever (nuvem, console e PC)<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Saindo em 5 de julho:<\/strong>\n<ul class=\"wp-block-list\">\n<li>Cricket 22 (nuvem, console e PC)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>A Microsoft anunciou uma s\u00e9rie de novos jogos que est\u00e3o chegando ao cat\u00e1logo do Game Pass. Confira os detalhes abaixo:&hellip;<\/p>\n","protected":false},"author":1,"featured_media":34601,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/06\/GamePass_Hero_PT_BR-1b7294855711d9332de1.png?fit=1596%2C898&ssl=1","fifu_image_alt":"","footnotes":""},"categories":[443,4,18,14],"tags":[],"class_list":["post-34599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-games","category-noticias","category-pc","category-xbox"],"_links":{"self":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts\/34599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/comments?post=34599"}],"version-history":[{"count":1,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts\/34599\/revisions"}],"predecessor-version":[{"id":34600,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts\/34599\/revisions\/34600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/media\/34601"}],"wp:attachment":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/media?parent=34599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/categories?post=34599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/tags?post=34599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}