{"id":36641,"date":"2024-12-03T23:13:12","date_gmt":"2024-12-04T02:13:12","guid":{"rendered":"https:\/\/revolutionarena.com\/pt-br\/?p=36641"},"modified":"2024-12-03T23:38:37","modified_gmt":"2024-12-04T02:38:37","slug":"xbox-permitira-jogar-indiana-jones-e-o-grande-circulo-e-outros-jogos-antes-do-lancamento-na-ccxp24","status":"publish","type":"post","link":"https:\/\/revolutionarena.com\/pt-br\/xbox-permitira-jogar-indiana-jones-e-o-grande-circulo-e-outros-jogos-antes-do-lancamento-na-ccxp24\/","title":{"rendered":"Xbox permitir\u00e1 jogar Indiana Jones e o Grande C\u00edrculo e outros jogos, antes do lan\u00e7amento, na CCXP24"},"content":{"rendered":"\n<p>A Xbox anunciou sua participa\u00e7\u00e3o na CCXP24, que ocorre de 5 a 8 de dezembro em S\u00e3o Paulo, trazendo uma s\u00e9rie de atra\u00e7\u00f5es, incluindo a possibilidade de jogar o aguardado <em>Indiana Jones e o Grande C\u00edrculo\u2122<\/em> antes de seu lan\u00e7amento oficial em 9 de dezembro. Al\u00e9m disso, os visitantes ter\u00e3o acesso a uma variedade de jogos in\u00e9ditos e lan\u00e7ados recentemente, al\u00e9m de atividades interativas no estande da marca.<\/p>\n\n\n\n<p>Durante o evento, os f\u00e3s poder\u00e3o experimentar <em>Indiana Jones e o Grande C\u00edrculo<\/em>, mergulhando em uma aventura cheia de explora\u00e7\u00e3o, enigmas e a\u00e7\u00e3o cl\u00e1ssica do famoso arque\u00f3logo. Outros t\u00edtulos in\u00e9ditos, como <em>Little Nightmares III<\/em>, <em>The Alters<\/em>, <em>REPLACED<\/em>, <em>One Card One Shot \u2013 Mafia<\/em> e o jogo brasileiro <em>Master Lemon: The Quest for Iceland<\/em>, estar\u00e3o dispon\u00edveis para testes antes de seus lan\u00e7amentos em 2025.<\/p>\n\n\n\n<p>Jogos j\u00e1 lan\u00e7ados tamb\u00e9m far\u00e3o parte da experi\u00eancia, incluindo <em>Fallout 76: Profundezas Brilhantes<\/em>, <em>Call of Duty: Black Ops 6<\/em>, <em>Microsoft Flight Simulator 2024<\/em> e <em>S.T.A.L.K.E.R. 2: Heart of Chornobyl<\/em>. Com mais de 80 esta\u00e7\u00f5es, o estande promete agradar tanto os entusiastas de jogos hardcore quanto os jogadores casuais, com t\u00edtulos como <em>Fortnite<\/em>, <em>Mortal Kombat 1<\/em>, <em>EA SPORTS FC 25<\/em> e <em>Dragon Ball: Sparking! Zero<\/em>.<\/p>\n\n\n\n<p><em><strong>Indiana Jones e o Grande C\u00edrculo<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/IndianaJones_Hero-Key-Art_4K-7e5aa74cad51792d2537.jpg?resize=1024%2C576&amp;ssl=1\" alt=\"\" class=\"wp-image-16742\"\/><\/figure>\n\n\n\n<p>Viva a aventura como Indy em uma hist\u00f3ria emocionante cheia de explora\u00e7\u00e3o, a\u00e7\u00e3o imersiva e quebra-cabe\u00e7as intrigantes. Como o brilhante arque\u00f3logo conhecido pelo intelecto agu\u00e7ado, engenhosidade, ast\u00facia e humor caracter\u00edstico, voc\u00ea viajar\u00e1 pelo mundo em uma corrida contra for\u00e7as inimigas para descobrir os segredos de um dos maiores mist\u00e9rios de todos os tempos.<\/p>\n\n\n\n<p><em><strong>Little Nightmares III<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/LN3-no-logo-fb5a0f311a9e060e7213.jpg?resize=1024%2C546&amp;ssl=1\" alt=\"\" class=\"wp-image-16743\"\/><\/figure>\n\n\n\n<p>Em&nbsp;<em>Little Nightmares III<\/em>, vivencie a jornada de Low e Alone e ajude-os a escapar. Os dois amigos est\u00e3o presos dentro da Espiral, um aglomerado de lugares perturbadores, e precisam trabalhar em equipe para sobreviver num mundo perigoso cheio de ilus\u00f5es e fugir das garras de uma amea\u00e7a ainda maior que os espreita nas sombras.<\/p>\n\n\n\n<p><em><strong>The Alters<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/the-alters-5pkdm-79589099ba0340f20448.jpg?resize=1024%2C576&amp;ssl=1\" alt=\"\" class=\"wp-image-16744\"\/><\/figure>\n\n\n\n<p>Jan Dolski \u00e9 um trabalhador comum que encara probabilidades imposs\u00edveis. Aterrissando de emerg\u00eancia em um planeta distante, perdido e sozinho, ele parece estar em uma situa\u00e7\u00e3o sem sa\u00edda. A \u00fanica esperan\u00e7a de sobreviv\u00eancia de Jan \u00e9 conseguir mais ajuda para sua base m\u00f3vel\u2026 mas como? Adaptando-se conforme avan\u00e7a, Jan usa a subst\u00e2ncia local Rapidium para criar vers\u00f5es alternativas de si mesmo: OS ALTERS.<\/p>\n\n\n\n<p><em><strong>REPLACED<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/Replaced_Keyart_Landscape_16x9-2df624b8e9e54c9c44a1-b8bccb0fc9ddbf9228bd.jpg?resize=1024%2C578&amp;ssl=1\" alt=\"\" class=\"wp-image-16745\"\/><\/figure>\n\n\n\n<p><em>REPLACED<\/em>&nbsp;\u00e9 um jogo de fic\u00e7\u00e3o cient\u00edfica retro-futurista de a\u00e7\u00e3o em plataformas 2.5D, no qual voc\u00ea assume o papel de R.E.A.C.H. \u2013 uma intelig\u00eancia artificial presa involuntariamente em um corpo humano.<\/p>\n\n\n\n<p><em><strong>Master Lemon: The Quest for Iceland<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/Master-Lemon-9c37cab10599faf06ffe.jpg?resize=1024%2C576&amp;ssl=1\" alt=\"\" class=\"wp-image-16746\"\/><\/figure>\n\n\n\n<p><em>Master Lemon<\/em>&nbsp;\u00e9 um jogo de aventura narrativa inspirado em uma hist\u00f3ria real. Os jogadores resolvem quebra-cabe\u00e7as e enfrentam escolhas dif\u00edceis enquanto Lemon tenta salvar uma terra de uma praga que devora mem\u00f3rias e amea\u00e7a o legado de todas as l\u00ednguas do mundo.<\/p>\n\n\n\n<p><em><strong>One Card One Shot \u2013 Mafia<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/One-Card-One-Shot-9aa0dd3fd7f013fca126.jpg?resize=1024%2C576&amp;ssl=1\" alt=\"\" class=\"wp-image-16747\"\/><\/figure>\n\n\n\n<p>Explore o submundo da m\u00e1fia em uma mistura eletrizante de Card Game e Sniper! R\u00e1pido e intuitivo, perfeito para uma divers\u00e3o r\u00e1pida ou horas de jogo. Escolha sua miss\u00e3o, monte seu deck e enfrente desafios at\u00e9 derrubar o chefe da m\u00e1fia. Cada carta virada reserva surpresas.<\/p>\n\n\n\n<p><em><strong>Call of Duty: Black Ops 6<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/CoD_BO6-fa76908ba301fba554c2.jpg?resize=1024%2C576&amp;ssl=1\" alt=\"\" class=\"wp-image-16748\"\/><\/figure>\n\n\n\n<p>A Campanha de&nbsp;<em>Black Ops 6<\/em>&nbsp;entrega jogabilidade din\u00e2mica a todo instante, incluindo v\u00e1rios espa\u00e7os de jogo com cen\u00e1rios de grande sucesso e momentos carregados de a\u00e7\u00e3o, assaltos de alto risco e intrigantes opera\u00e7\u00f5es de espionagem. Na melhor experi\u00eancia multiplayer da categoria, jogadores v\u00e3o testar suas habilidades em 16 mapas.<\/p>\n\n\n\n<p><em><strong>Microsoft Flight Simulator 2024<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/MSFS2024-7f00198b5ba133abe1ef.jpg?resize=1024%2C576&amp;ssl=1\" alt=\"\" class=\"wp-image-16749\"\/><\/figure>\n\n\n\n<p>Explore o mundo com a nossa maior frota de avi\u00f5es Standard Edition e leve a simula\u00e7\u00e3o a novas alturas em sua carreira de aviador com o&nbsp;<em>Microsoft Flight Simulator 2024<\/em>. nicie sua carreira na avia\u00e7\u00e3o em qualquer lugar do mundo. Obtenha experi\u00eancia, desenvolva sua reputa\u00e7\u00e3o e complete certifica\u00e7\u00f5es para obter acesso a atividades de avia\u00e7\u00e3o aut\u00eanticas, de evacua\u00e7\u00f5es m\u00e9dicas, opera\u00e7\u00f5es de frete remoto, combate a\u00e9reo, busca e resgate e muito mais ao longo da sua jornada para se tornar um piloto de transporte de passageiros de linha a\u00e9rea. Inicie uma aventura de avia\u00e7\u00e3o verdadeiramente global com miss\u00f5es praticamente ilimitadas em todo o mundo.<\/p>\n\n\n\n<p><em><strong>S.T.A.L.K.E.R. 2: Heart of Chornobyl<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/STALKER-2-faddf5ea7ec6ddaeda97-c3b9e9e19b20b876b358.jpg?resize=1024%2C576&amp;ssl=1\" alt=\"\" class=\"wp-image-16750\"\/><\/figure>\n\n\n\n<p><em>S.T.A.L.K.E.R. 2: Heart of Chornobyl<\/em>&nbsp;\u00e9 uma aventura imperdo\u00e1vel de sobreviv\u00eancia FPS em um mundo aberto e sombrio de fic\u00e7\u00e3o cient\u00edfica. Vasculhe em busca de equipamentos e recursos, cace por recompensas, fa\u00e7a decis\u00f5es complexas para sobreviver e crie o seu pr\u00f3prio caminho pela Zona An\u00f4mala de Chornobyl.<\/p>\n\n\n\n<p><em><strong>Age of Mythology: Retold<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/Age-Mythology-0dd483128775e98c9f41.jpg?resize=1024%2C576&amp;ssl=1\" alt=\"\" class=\"wp-image-16751\"\/><\/figure>\n\n\n\n<p>Dos criadores da premiada franquia&nbsp;<em>Age of Empires<\/em>,&nbsp;<em>Age of Mythology: Retold<\/em>&nbsp;vai al\u00e9m da hist\u00f3ria para uma era m\u00edtica onde deuses, monstros e humanos colidem. Combinando os melhores elementos da amada Era da Mitologia com design e visuais modernos de estrat\u00e9gia em tempo real, Retold \u00e9 uma experi\u00eancia \u00e9pica e inovadora para jogadores antigos e novos. Proteja seu dom\u00ednio, comande monstros lend\u00e1rios e recorra ao poder dos deuses para esmagar seus inimigos.<\/p>\n\n\n\n<p><strong><em>Forza Horizon 5<\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/ForzaHorizon5_-e45d0daaad1db7784f00-1024x576.jpg?resize=1024%2C576&amp;ssl=1\" alt=\"\" class=\"wp-image-16752\"\/><\/figure>\n\n\n\n<p>Sua maior aventura Horizon espera por voc\u00ea! Explore as paisagens vibrantes de mundo aberto do M\u00e9xico, com divers\u00e3o e velocidade sem limites em um mundo em constante evolu\u00e7\u00e3o, incluindo centenas dos melhores carros do mundo. Participe de um jogo de persegui\u00e7\u00e3o emocionante com a nossa nova Experi\u00eancia multiplayer 5 contra 1, Esconde-Esconde!<\/p>\n\n\n\n<p><em><strong>Minecraft<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/Minecraft_-9a2a467bd4f4d0834ab8.jpg?resize=1024%2C576&amp;ssl=1\" alt=\"\" class=\"wp-image-16753\"\/><\/figure>\n\n\n\n<p>Construa tudo o que voc\u00ea puder imaginar no seu pr\u00f3prio mundo infinito, exclusivo em cada jogo. Descubra biomas, recursos e multid\u00f5es e abra caminho por um mundo repleto de surpresas no jogo de \u00e1rea restrita final. Experimente aventuras inesquec\u00edveis enquanto enfrenta inimigos misteriosos, atravessa paisagens incr\u00edveis e viaja para dimens\u00f5es perigosas.<\/p>\n\n\n\n<p><em><strong>Fallout 76: Profundezas Brilhantes<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/Fallout76_-50eeb982c9b41f8978ed.jpg?resize=1024%2C464&amp;ssl=1\" alt=\"\" class=\"wp-image-16754\"\/><\/figure>\n\n\n\n<p>A Bethesda Game Studios, premiada criadora de&nbsp;<em>Skyrim<\/em>&nbsp;e&nbsp;<em>Fallout 4<\/em>, apresenta o&nbsp;<em>Fallout 76<\/em>. Explore os ermos devastados pela guerra nuclear neste suplemento multijogador de mundo aberto da hist\u00f3ria de Fallout.<\/p>\n\n\n\n<p><em><strong>Sea of Thieves<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/SoT_KeyArt-a06e8e4328b30261eb47.jpg?resize=1024%2C576&amp;ssl=1\" alt=\"\" class=\"wp-image-16755\"\/><\/figure>\n\n\n\n<p><em>Sea of Thieves<\/em>&nbsp;\u00e9 um jogo de aventura pirata de sucesso, que oferece a experi\u00eancia de pilhar tesouros perdidos, fazer parte de batalhas intensas, derrotar monstros marinhos e muito mais.<\/p>\n\n\n\n<p><em><strong>Diablo Immortal<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/Diablo-Immortal-d01e37b2c73e8cebab3f.jpg?resize=1024%2C592&amp;ssl=1\" alt=\"\" class=\"wp-image-16756\"\/><\/figure>\n\n\n\n<p>A Blizzard Entertainment traz at\u00e9 voc\u00ea a emblem\u00e1tica s\u00e9rie de RPG de a\u00e7\u00e3o situada entre os eventos de&nbsp;<em>Diablo II: Lord of Destruction<\/em>&nbsp;e&nbsp;<em>Diablo III<\/em>. Desde o lan\u00e7amento, Diablo Immortal vem contando com atualiza\u00e7\u00f5es frequentes, incluindo novas zonas, equipamentos e eventos competitivos, al\u00e9m de mais hist\u00f3rias demon\u00edacas para voc\u00ea vivenciar, e a primeira nova classe jog\u00e1vel na franquia Diablo desde 2014. Encare ex\u00e9rcitos de dem\u00f4nios, colete esp\u00f3lios \u00e9picos e ganhe poderes inimagin\u00e1veis.<\/p>\n\n\n\n<p><em><strong>League of Legends<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/League-of-Legends-Hero-7dd00715fc266f286426.jpg?resize=1024%2C576&amp;ssl=1\" alt=\"\" class=\"wp-image-16757\"\/><\/figure>\n\n\n\n<p>Mostre suas habilidades na melhor arena de batalha 5v5, que combina estrat\u00e9gias em equipe com maestria solo. Escolha sua fun\u00e7\u00e3o, otimize sua itemiza\u00e7\u00e3o e abra caminho pelo mapa para destruir o Nexus inimigo. Sempre gr\u00e1tis para jogar \u2014 que a melhor equipe ven\u00e7a!<\/p>\n\n\n\n<p><em><strong>Valorant<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/Valorant-Hero-53fb590dde7bcf657e8a.jpg?resize=1024%2C576&amp;ssl=1\" alt=\"\" class=\"wp-image-16758\"\/><\/figure>\n\n\n\n<p><em>Valorant<\/em>&nbsp;\u00e9 um FPS t\u00e1tico 5\u00d75 focado em personagens que se passa no mundo todo. Fa\u00e7a jogadas incr\u00edveis e supere seus oponentes com habilidades t\u00e1ticas, mec\u00e2nica de tiro e trabalho em equipe. Misture o seu estilo e experi\u00eancia em um cen\u00e1rio global e competitivo. Voc\u00ea ter\u00e1 13 rodadas para atacar e defender com disparos certeiros e habilidades t\u00e1ticas. Com apenas uma vida por rodada, voc\u00ea deve pensar mais r\u00e1pido que o oponente se quiser sobreviver.<\/p>\n\n\n\n<p><em><strong>Fortnite<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/fortnite-battle-royale-1920x1080-864336699-e814a86211c4e117eba6-1024x576.jpg?resize=1024%2C576&amp;ssl=1\" alt=\"\" class=\"wp-image-16759\"\/><\/figure>\n\n\n\n<p>Seja a \u00faltima pessoa de p\u00e9 no Battle Royale, na Troca\u00e7\u00e3o e no Reload, explore e sobreviva no&nbsp;<em>LEGO Fortnite<\/em>, chegue voando \u00e0 linha de chegada no&nbsp;<em>Rocket Racing<\/em>&nbsp;ou arranque aplausos num show no&nbsp;<em>Fortnite Festival<\/em>. Jogue milhares de Ilhas gr\u00e1tis feitas por criadores, incluindo jogos no estilo corrida mortal, magnata, sobreviv\u00eancia zumbi e mais! Junte-se \u00e0 comunidade de cria\u00e7\u00e3o e construa sua pr\u00f3pria Ilha com o Unreal Editor para Fortnite (UEFN) ou as Ferramentas do Modo Criativo do&nbsp;<em>Fortnite<\/em>.<\/p>\n\n\n\n<p><em><strong>Palworld<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/Palworld_KeyVisual_1080p_Loco_C-06386fa765966ebbb9d2.jpg?resize=1024%2C576&amp;ssl=1\" alt=\"\" class=\"wp-image-16760\"\/><\/figure>\n\n\n\n<p>Este \u00e9 um jogo em que voc\u00ea pode tanto levar uma vida tranquila junto de criaturas fant\u00e1sticas conhecidas como \u201cPals\u201d quanto envolver-se em confrontos arriscados contra ca\u00e7adores clandestinos. Os Pals podem ser usados em batalhas, para procria\u00e7\u00e3o ou at\u00e9 como ajudantes de trabalho em fazendas e f\u00e1bricas.<\/p>\n\n\n\n<p><em><strong>Goat Simulator Remastered<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/XBOX_GoatSimulatorRemastered_TitledHeroArt_1920x1080-f620478f2d4723a23ccf.jpg?resize=1024%2C576&amp;ssl=1\" alt=\"\" class=\"wp-image-16761\"\/><\/figure>\n\n\n\n<p>O&nbsp;<em>Goat Simulator Remastered<\/em>&nbsp;\u00e9 a \u00faltima palavra em simula\u00e7\u00e3o de cabras. Sua ca\u00f3tica sandbox favorita est\u00e1 de volta e mais linda que nunca, com gr\u00e1ficos atualizados, todos os DLCs e mais bugs do que pulgas numa cabra. Seu objetivo? O caos! Sua musa? Pilgor, a cabra! Se voc\u00ea passou os \u00faltimos 10 anos vivendo num curral, Goat Simulator \u00e9 um jogo sobre causar o m\u00e1ximo de destrui\u00e7\u00e3o poss\u00edvel enquanto controla uma cabra. D\u00ea cabe\u00e7adas, mortais para tr\u00e1s e se jogue em cada fase para ganhar pontos e encontrar maneiras criativas de arruinar o dia de um NPC.<\/p>\n\n\n\n<p><em><strong>Mortal Kombat 1<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/MK1_Hero-65b206e1491415342b06.jpg?resize=1024%2C576&amp;ssl=1\" alt=\"\" class=\"wp-image-16762\"\/><\/figure>\n\n\n\n<p>Descubra um Universo renascido de Mortal&nbsp;Kombat criado pelo Deus do Fogo Liu Kang.&nbsp;<em>Mortal&nbsp;Kombat&nbsp;1<\/em>&nbsp;inaugura uma nova era da franquia ic\u00f4nica com um novo sistema de luta, modos de jogo e fatalities!<\/p>\n\n\n\n<p><em><strong>Star Wars Outlaws<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/Outlaws_30346_Keyart_horizontal_RGB_WW_JPG-1c185c951e9ab976e112.jpg?resize=1024%2C576&amp;ssl=1\" alt=\"\" class=\"wp-image-16763\"\/><\/figure>\n\n\n\n<p>Vivencie o primeiro jogo de a\u00e7\u00e3o e aventura de mundo aberto de Star Wars e explore locais distintos pela gal\u00e1xia, tanto lend\u00e1rios quanto novos. Arrisque tudo como a trapaceira Kay Vess, em busca de liberdade e dos meios para come\u00e7ar uma nova vida. Lute, roube e trapaceie pelo submundo enquanto enfrenta os sindicatos criminosos da gal\u00e1xia.<\/p>\n\n\n\n<p><em><strong>Genshin Impact<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/Genshin-791b432f7919fe548bfc.jpg?resize=1024%2C576&amp;ssl=1\" alt=\"\" class=\"wp-image-16764\"\/><\/figure>\n\n\n\n<p><em>Genshin Impact<\/em>&nbsp;\u00e9 um jogo RPG de aventura de mundo aberto. No jogo voc\u00ea explorar\u00e1 um mundo fant\u00e1stico chamado Teyvat. Neste mundo grande e amplo, voc\u00ea pode visitar as sete cidades e encontrar parceiros com suas pr\u00f3prias caracter\u00edsticas e habilidades \u00fanicas. Lute com eles contra inimigos poderosos e procure seu ente perdido.<\/p>\n\n\n\n<p><em><strong>EA SPORTS FC 25<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/EA-Sports-FC25-b9a123338053031c234a.jpg?resize=1024%2C576&amp;ssl=1\" alt=\"\" class=\"wp-image-16765\"\/><\/figure>\n\n\n\n<p>O&nbsp;<em>EA SPORTS FC 25<\/em>&nbsp;oferece mais maneiras de ganhar pelo clube. Jogue em equipe no modo 5\u00d75 do Rush, uma nova maneira de jogar com suas amizades nos modos Football Ultimate Team, Clubs e Jogo R\u00e1pido com partidas curtas. No Rush do Football Ultimate Team, monte seu time de 5 dos sonhos com at\u00e9 tr\u00eas amizades, com cada pessoa controlando o Item de Atleta favorito.<\/p>\n\n\n\n<p><em><strong>Dragon Ball: Sparking! Zero<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/dragon-ball-sparking-zero-4b07614fb5369a2276cb.jpg?resize=1024%2C538&amp;ssl=1\" alt=\"\" class=\"wp-image-16766\"\/><\/figure>\n\n\n\n<p><em>Dragon Ball: Sparking!&nbsp;<\/em><em>Zero<\/em>&nbsp;pegou a jogabilidade lend\u00e1ria da s\u00e9rie&nbsp;<em>Budokai Tenkaichi<\/em>&nbsp;e a elevou a novos n\u00edveis. Torne-se um superguerreiro e vivencie as batalhas de tremer a terra e romper limites de Dragon Ball! Desperte o poder de mais de 180 lutadores de Dragon Ball Z, Dragon Ball Super, Dragon Ball GT e dos filmes selecionados de Dragon Ball, tudo no jogo de base! Cada personagem tem suas pr\u00f3prias habilidades especiais, transforma\u00e7\u00f5es e t\u00e9cnicas.<\/p>\n\n\n\n<p><em><strong>Metaphor: ReFantazio<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/Metaphor_Hero-e09ba500e496b7817c94-1024x576.jpg?resize=1024%2C576&amp;ssl=1\" alt=\"\" class=\"wp-image-16767\"\/><\/figure>\n\n\n\n<p><em>Metaphor: ReFantazio<\/em>&nbsp;\u00e9 um RPG de fantasia que leva os jogadores a aventuras emocionantes em um mundo onde oito tribos vivem em conflito e o trono est\u00e1 abandonado ap\u00f3s o assassinato do rei. Sem herdeiros para a coroa, o desejo do falecido rei decreta que o pr\u00f3ximo monarca ser\u00e1 eleito pelo povo, dando in\u00edcio \u00e0 luta pelo trono\u2026 e pelo futuro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Experi\u00eancias exclusivas e programa\u00e7\u00e3o especial<\/h3>\n\n\n\n<p>O espa\u00e7o \u201cIsso \u00e9 um Xbox\u201d destacar\u00e1 a versatilidade da marca, com jogos rodando em dispositivos de parceiros como Samsung, Logitech, Asus e Dell, mostrando o alcance da plataforma Xbox em consoles, PCs e dispositivos m\u00f3veis. Al\u00e9m disso, no Palco Omelete, desenvolvedores de jogos aguardados, como <em>Avowed<\/em> e <em>Indiana Jones e o Grande C\u00edrculo\u2122<\/em>, apresentar\u00e3o detalhes e bastidores de seus projetos. As apresenta\u00e7\u00f5es ocorrer\u00e3o na quinta-feira, 5 de dezembro, e ser\u00e3o transmitidas ao vivo nos canais oficiais da CCXP24.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Informa\u00e7\u00f5es sobre a CCXP24<\/h3>\n\n\n\n<p>O evento acontecer\u00e1 no S\u00e3o Paulo Expo, na Rodovia dos Imigrantes, com funcionamento das 12h \u00e0s 21h de quinta e sexta-feira, das 11h \u00e0s 21h no s\u00e1bado, e das 11h \u00e0s 20h no domingo. A presen\u00e7a da Xbox na CCXP24 promete ser um dos grandes destaques, oferecendo aos f\u00e3s uma oportunidade \u00fanica de explorar lan\u00e7amentos, interagir com desenvolvedores e vivenciar o futuro dos jogos em primeira m\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Xbox anunciou sua participa\u00e7\u00e3o na CCXP24, que ocorre de 5 a 8 de dezembro em S\u00e3o Paulo, trazendo uma&hellip;<\/p>\n","protected":false},"author":1,"featured_media":36643,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"https:\/\/i0.wp.com\/xxboxnews.blob.core.windows.net\/prod\/sites\/8\/2024\/12\/IndianaJones-Keyart-PTbr_HERO-e0f5f081314bb013814d.jpg?fit=1920%2C1080&ssl=1","fifu_image_alt":"","footnotes":""},"categories":[23,443,4,14],"tags":[],"class_list":["post-36641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-games","category-noticias","category-xbox"],"_links":{"self":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts\/36641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/comments?post=36641"}],"version-history":[{"count":3,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts\/36641\/revisions"}],"predecessor-version":[{"id":36645,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/posts\/36641\/revisions\/36645"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/media\/36643"}],"wp:attachment":[{"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/media?parent=36641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/categories?post=36641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revolutionarena.com\/pt-br\/wp-json\/wp\/v2\/tags?post=36641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}